{"id":93,"count":5,"description":"","link":"https:\/\/amazonia-teamfactory.com\/blog\/category\/habilidades-directivas\/","name":"habilidades directivas","slug":"habilidades-directivas","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/categories\/93","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/posts?categories=93"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}