{"id":3304,"date":"2014-10-13T06:25:31","date_gmt":"2014-10-13T05:25:31","guid":{"rendered":"https:\/\/amazonia-teamfactory.com\/blog\/?p=3304"},"modified":"2025-10-15T10:09:52","modified_gmt":"2025-10-15T08:09:52","slug":"equipo-mas-que-suma-miembros","status":"publish","type":"post","link":"https:\/\/amazonia-teamfactory.com\/blog\/equipo-mas-que-suma-miembros\/","title":{"rendered":"El equipo es mucho m\u00e1s que la suma de sus miembros"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En el <a href=\"https:\/\/amazonia-teamfactory.com\/formacion\/team-building-madrid\/\">team building<\/a>, a menudo tratamos las diferentes mec\u00e1nicas que se originan dentro de los grupos y que determinan su <strong>cohesi\u00f3n y rendimiento<\/strong> desde el punto de vista de los equipos deportivos.<\/p>\n\n\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3305\" src=\"https:\/\/amazonia-teamfactory.com\/blog\/wp-content\/uploads\/equipo-mas-que-suma-miembros.jpg\" alt=\"Equipo m\u00e1s que suma miembros\" width=\"640\" height=\"426\" \/><\/p>\n<p>Por supuesto, esto no es al azar. Resulta que un <strong>deporte de equipo<\/strong> es, por definici\u00f3n, una competici\u00f3n entre grupos de personas que confrontan sus capacidades individuales y colectivas para alcanzar un bien com\u00fan. Si un equipo desempe\u00f1a mejor su tarea que su rival, resulta vencedor. Los deportes de equipo constituyen, por tanto, un excelente espejo donde mirarse para comprender algunos puntos d\u00e9biles o fuertes de los grupos de personas.<\/p>\n<p><!--more--><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/amazonia-teamfactory.com\/blog\/equipo-mas-que-suma-miembros\/#El_equipo_de_trabajo\" >El equipo de trabajo<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/amazonia-teamfactory.com\/blog\/equipo-mas-que-suma-miembros\/#Mucho_mas_que_la_suma_de_sus_partes\" >Mucho m\u00e1s que la suma de sus partes<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/amazonia-teamfactory.com\/blog\/equipo-mas-que-suma-miembros\/#1_Falta_de_compromiso_con_el_proyecto\" >1) Falta de compromiso con el proyecto<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/amazonia-teamfactory.com\/blog\/equipo-mas-que-suma-miembros\/#2_Prevalencia_del_%E2%80%9Cyo%E2%80%9D_por_encima_del_%E2%80%9Cnosotros%E2%80%9D\" >2) Prevalencia del \u201cyo\u201d por encima del \u201cnosotros\u201d<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/amazonia-teamfactory.com\/blog\/equipo-mas-que-suma-miembros\/#3_Falta_de_liderazgo\" >3) Falta de liderazgo<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/amazonia-teamfactory.com\/blog\/equipo-mas-que-suma-miembros\/#4_Sobreexposicion\" >4) Sobreexposici\u00f3n<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"El_equipo_de_trabajo\"><\/span>El equipo de trabajo<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>En este art\u00edculo, vamos a fijarnos en un hecho importante y nos vamos a apoyar en argumentos deportivos: <strong>el equipo es mucho m\u00e1s que la suma de sus miembros<\/strong>.<\/p>\n<p>En los deportes colectivos existen innumerables ejemplos de equipos inferiores que vencieron a equipos superiores. Los equipos superiores son considerados as\u00ed por contar con m\u00e1s presupuesto que les permite acceder a mejores jugadores, mejores l\u00edderes, mejores instalaciones o un mejor personal de apoyo. Y sin embargo, en ocasiones son derrotados por otros equipos que no disponen de tantos medios. \u00bfPor qu\u00e9?<\/p>\n<p>Esto puede ocurrir puntualmente, y una explicaci\u00f3n sencilla para que pase es achacarlo todo a la <a title=\"Art\u00edculos sobre motivaci\u00f3n\" href=\"https:\/\/amazonia-teamfactory.com\/blog\/tag\/motivacion-2\/\">motivaci\u00f3n<\/a>. Cuando un equipo inferior se enfrenta a uno superior normalmente se siente especialmente motivado debido a que una victoria en estas circunstancias constituye un aliciente mayor. Esta explicaci\u00f3n tambi\u00e9n funciona en el sentido inverso: ocurre con frecuencia que un equipo superior no se siente motivado al enfrentarse a un equipo inferior.<\/p>\n<p>Lo sorprendente es cuando esta situaci\u00f3n se prolonga de forma extraordinaria a lo largo del tiempo. Hablo de esos ejemplos en los que un equipo manifiestamente inferior a otros alcanza el triunfo en una competici\u00f3n de larga duraci\u00f3n o en los que equipos manifiestamente superiores fracasan estrepitosamente.<\/p>\n<p>Vamos a exponer dos casos contrapuestos de la misma teor\u00eda.<\/p>\n<p>Por un lado, vamos a hablar de <strong>un equipo que lo ten\u00eda todo<\/strong> a favor para alcanzar sus objetivos y no lo logr\u00f3 porque el equipo nunca lleg\u00f3 a ser m\u00e1s que la suma de sus miembros.<\/p>\n<p>El mes que viene hablaremos del ejemplo contrario, un equipo que cuyos miembros eran claramente inferiores en t\u00e9rminos deportivos a muchos los de los equipos de su entorno, rompieron la barrera de ser individuos y multiplicaron su potencial al convertirse en un equipo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Mucho_mas_que_la_suma_de_sus_partes\"><\/span>Mucho m\u00e1s que la suma de sus partes<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Veamos el primer ejemplo tomando como referencia un equipo de futbol muy famoso conocido como \u201c<strong>El Madrid de los Gal\u00e1cticos<\/strong>\u201d, un ejemplo muy claro de por qu\u00e9 la suma de los miembros de un equipo siempre es inferior al valor total del equipo.<\/p>\n<p>Este <a href=\"https:\/\/javierdisan.com\/2016\/04\/06\/trabajo-equipo-menor-suma-partes\/\" target=\"_blank\" rel=\"noopener\">equipo<\/a> era llamado as\u00ed porque contaba con innumerables estrellas. T\u00e9cnicamente, dispon\u00edan de los mejores jugadores del mundo en sus respectivas posiciones. Sin embargo, sus logros estuvieron muy alejados de sus expectativas, incluso cuando sus objetivos estaban claramente definidos y no se repar\u00f3 en medios para alcanzarlos. \u00bfPor qu\u00e9?<\/p>\n<p>Sin entrar en valoraciones deportivas que no vienen al caso, a nivel de <strong>din\u00e1mica de grupo<\/strong> se dieron algunos factores que hicieron que aquel grupo de personas nunca alcanzara su potencial como equipo:<\/p>\n<h3><span class=\"ez-toc-section\" id=\"1_Falta_de_compromiso_con_el_proyecto\"><\/span><b>1) Falta de compromiso con el proyecto<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><b><\/b>Algunos componentes de ese equipo ven\u00edan de alcanzar el \u00e9xito en otros lugares y para ellos el proyecto era simplemente otro trabajo m\u00e1s. El no estar implicado en el proyecto hace que la motivaci\u00f3n nunca sea \u00f3ptima y se pierda con gran facilidad. La falta de motivaci\u00f3n puede llevar a la falta de rendimiento, a no alcanzar metas, al absentismo laboral. En definitiva, la <strong>falta de compromiso<\/strong> se traduce en una p\u00e9rdida de productividad.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"2_Prevalencia_del_%E2%80%9Cyo%E2%80%9D_por_encima_del_%E2%80%9Cnosotros%E2%80%9D\"><\/span><b>2) Prevalencia del \u201cyo\u201d por encima del \u201cnosotros\u201d<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p><b><\/b>Los <strong>egos personales<\/strong> hicieron muy dif\u00edcil gestionar el equipo, hasta el punto de que algunos entrenadores dimitieron porque no pod\u00edan controlar a las personas que se supone que deb\u00edan dirigir. La deficiente gesti\u00f3n del \u00abyo\u00bb conduce muchas veces a la creaci\u00f3n de bandos y camarillas dentro de los equipos que envenenan su din\u00e1mica. Es importante dentro de los equipos hacer comprender que <strong>la organizaci\u00f3n es un ente propio<\/strong> a la altura de los individuos, y que ser\u00e1 m\u00e1s beneficioso para el equipo en conjunto si todos sus miembros aparcan sus intereses personales en pro de un inter\u00e9s com\u00fan<\/p>\n<h3><span class=\"ez-toc-section\" id=\"3_Falta_de_liderazgo\"><\/span><b>3) Falta de liderazgo<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Como consecuencia del punto anterior, <strong>no exist\u00eda un l\u00edder<\/strong> lo bastante fuerte como para variar el rumbo de la nave si las cosas se torc\u00edan o para tomar decisiones dif\u00edciles o para mediar en la<strong> resoluci\u00f3n de conflicto<\/strong>s. No hablo de un gestor, director o entrenador, sino de una persona respetada por todos cuya opini\u00f3n es escuchada. Todos los equipos necesitan un l\u00edder en momentos de necesidad, aunque este l\u00edder no es necesariamente la persona que gestiona el equipo. El gestor, en el caso de no ser l\u00edder de un equipo, debe ser lo bastante inteligente como para hacerse apoyar por el l\u00edder.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"4_Sobreexposicion\"><\/span><b>4) Sobreexposici\u00f3n<\/b><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Un equipo formado por estrellas est\u00e1 muy expuesto a la opini\u00f3n p\u00fablica y atrae muchas m\u00e1s miradas que uno que no cuenta con miembros ilustres entre sus filas. Esto es un arma de doble filo, porque se intensifican las cr\u00edticas y los halagos que reciben el equipo en su totalidad. En el terreno laboral, es necesario proteger a los equipos de la <strong>sobreexposici\u00f3n ante la opini\u00f3n de compa\u00f1eros del sector<\/strong>, de jefes o directivos de la empresa e incluso de otros equipos similares dentro de la organizaci\u00f3n. Hay que relativizar las alabanzas y las cr\u00edticas para minimizar su impacto dentro del equipo.<\/p>\n<p>En el otro extremo, el mes que viene veremos como un equipo sin grandes medios puede <strong>alcanzar un alto rendimiento<\/strong> mediante el esfuerzo colectivo, la motivaci\u00f3n y el liderazgo eficaz.<\/p>","protected":false},"excerpt":{"rendered":"<p>A veces, equipos te\u00f3ricamente inferiores vencen a equipos superiores, \u00bfpor qu\u00e9? Porque ponen en marcha una serie de fuerzas internas dentro del equipo que lo convierten en mucho m\u00e1s que la suma de sus partes.<\/p>\n","protected":false},"author":2,"featured_media":8512,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12],"tags":[20,14,18,30],"class_list":["post-3304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-team-building-2","tag-cohesion","tag-compromiso-2","tag-liderazgo-2","tag-motivacion-2"],"_links":{"self":[{"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/posts\/3304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/comments?post=3304"}],"version-history":[{"count":0,"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/posts\/3304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/media\/8512"}],"wp:attachment":[{"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/media?parent=3304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/categories?post=3304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/amazonia-teamfactory.com\/blog\/wp-json\/wp\/v2\/tags?post=3304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}